     {"id":18266,"date":"2022-01-16T07:21:31","date_gmt":"2022-01-16T06:21:31","guid":{"rendered":"https:\/\/www.jobcloud.ch\/c\/de-ch\/?p=18266"},"modified":"2022-04-12T15:26:07","modified_gmt":"2022-04-12T13:26:07","slug":"vorlagen-fuer-stellenausschreibungen","status":"publish","type":"post","link":"https:\/\/www.jobcloud.ch\/c\/de-ch\/blog\/vorlagen-stellenausschreibungen\/","title":{"rendered":"Vorlagen f\u00fcr Stellenausschreibungen"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":27,"featured_media":18271,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[899],"tags":[1443,1444,1445,1446,1447,1448],"class_list":["post-18266","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recruiting","tag-inserat","tag-inseratvorlage","tag-jobinserat","tag-stellenausschreibung","tag-template","tag-vorlage"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vorlagen f\u00fcr Stellenausschreibungen | JobCloud<\/title>\n<meta name=\"description\" content=\"Auf JobCloud finden Sie unter \u00abRatgeber &amp; Checklisten\u00bb neu den Bereich \u00abVorlagen\u00bb. Entdecken Sie dort eine allgemeine Vorlage f\u00fcr eine Stellenausschreibung\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jobcloud.ch\/c\/de-ch\/blog\/vorlagen-stellenausschreibungen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vorlagen f\u00fcr Stellenausschreibungen | JobCloud\" \/>\n<meta property=\"og:description\" content=\"Auf JobCloud finden Sie unter \u00abRatgeber &amp; Checklisten\u00bb neu den Bereich \u00abVorlagen\u00bb. Entdecken Sie dort eine allgemeine Vorlage f\u00fcr eine Stellenausschreibung\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jobcloud.ch\/c\/de-ch\/blog\/vorlagen-stellenausschreibungen\/\" \/>\n<meta property=\"og:site_name\" content=\"JobCloud\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-16T06:21:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-12T13:26:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.jobcloud.ch\/wp-content\/uploads\/2019\/01\/rawpixel-1046262-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"719\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mathias Steger\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mathias Steger\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.jobcloud.ch\\\/c\\\/de-ch\\\/blog\\\/vorlagen-stellenausschreibungen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jobcloud.ch\\\/c\\\/de-ch\\\/blog\\\/vorlagen-stellenausschreibungen\\\/\"},\"author\":{\"name\":\"Mathias Steger\",\"@id\":\"https:\\\/\\\/www.jobcloud.ch\\\/c\\\/de-ch\\\/#\\\/schema\\\/person\\\/1f8af37d814987189cbef1b058a084a4\"},\"headline\":\"Vorlagen f\u00fcr Stellenausschreibungen\",\"datePublished\":\"2022-01-16T06:21:31+00:00\",\"dateModified\":\"2022-04-12T13:26:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.jobcloud.ch\\\/c\\\/de-ch\\\/blog\\\/vorlagen-stellenausschreibungen\\\/\"},\"wordCount\":4,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.jobcloud.ch\\\/c\\\/de-ch\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jobcloud.ch\\\/c\\\/de-ch\\\/blog\\\/vorlagen-stellenausschreibungen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.jobcloud.ch\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/rawpixel-1046262-1.jpg\",\"keywords\":[\"Inserat\",\"Inseratvorlage\",\"Jobinserat\",\"Stellenausschreibung\",\"Template\",\"Vorlage\"],\"articleSection\":[\"Recruiting\"],\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.jobcloud.ch\\\/c\\\/de-ch\\\/blog\\\/vorlagen-stellenausschreibungen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jobcloud.ch\\\/c\\\/de-ch\\\/blog\\\/vorlagen-stellenausschreibungen\\\/\",\"url\":\"https:\\\/\\\/www.jobcloud.ch\\\/c\\\/de-ch\\\/blog\\\/vorlagen-stellenausschreibungen\\\/\",\"name\":\"Vorlagen f\u00fcr Stellenausschreibungen | JobCloud\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jobcloud.ch\\\/c\\\/de-ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jobcloud.ch\\\/c\\\/de-ch\\\/blog\\\/vorlagen-stellenausschreibungen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jobcloud.ch\\\/c\\\/de-ch\\\/blog\\\/vorlagen-stellenausschreibungen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.jobcloud.ch\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/rawpixel-1046262-1.jpg\",\"datePublished\":\"2022-01-16T06:21:31+00:00\",\"dateModified\":\"2022-04-12T13:26:07+00:00\",\"description\":\"Auf JobCloud finden Sie unter \u00abRatgeber & Checklisten\u00bb neu den Bereich \u00abVorlagen\u00bb. Entdecken Sie dort eine allgemeine Vorlage f\u00fcr eine Stellenausschreibung\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jobcloud.ch\\\/c\\\/de-ch\\\/blog\\\/vorlagen-stellenausschreibungen\\\/#breadcrumb\"},\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.jobcloud.ch\\\/c\\\/de-ch\\\/blog\\\/vorlagen-stellenausschreibungen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/www.jobcloud.ch\\\/c\\\/de-ch\\\/blog\\\/vorlagen-stellenausschreibungen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.jobcloud.ch\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/rawpixel-1046262-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.jobcloud.ch\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/rawpixel-1046262-1.jpg\",\"width\":1400,\"height\":719},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jobcloud.ch\\\/c\\\/de-ch\\\/blog\\\/vorlagen-stellenausschreibungen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Wettbewerbskommission stimmt \u00dcbernahme von jobs.ch durch Ringier und Tamedia zu\",\"item\":\"https:\\\/\\\/www.jobcloud.ch\\\/c\\\/de-ch\\\/blog\\\/press-release\\\/wettbewerbskommission-stimmt-ubernahme-von-jobs-ch-durch-ringier-und-tamedia-zu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vorlagen f\u00fcr Stellenausschreibungen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jobcloud.ch\\\/c\\\/de-ch\\\/#website\",\"url\":\"https:\\\/\\\/www.jobcloud.ch\\\/c\\\/de-ch\\\/\",\"name\":\"JobCloud\",\"description\":\"JobCloud is the leading job portal for jobseekers in Switzerland\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jobcloud.ch\\\/c\\\/de-ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.jobcloud.ch\\\/c\\\/de-ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jobcloud.ch\\\/c\\\/de-ch\\\/#organization\",\"name\":\"JobCloud\",\"url\":\"https:\\\/\\\/www.jobcloud.ch\\\/c\\\/de-ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/www.jobcloud.ch\\\/c\\\/de-ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.jobcloud.ch\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/jobcloude-logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.jobcloud.ch\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/jobcloude-logo.svg\",\"width\":160,\"height\":37,\"caption\":\"JobCloud\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jobcloud.ch\\\/c\\\/de-ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jobcloud.ch\\\/c\\\/de-ch\\\/#\\\/schema\\\/person\\\/1f8af37d814987189cbef1b058a084a4\",\"name\":\"Mathias Steger\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/www.jobcloud.ch\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Mathias-Steger_avatar-96x96.png\",\"url\":\"https:\\\/\\\/www.jobcloud.ch\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Mathias-Steger_avatar-96x96.png\",\"contentUrl\":\"https:\\\/\\\/www.jobcloud.ch\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Mathias-Steger_avatar-96x96.png\",\"caption\":\"Mathias Steger\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/mathias-steger-52164a11b?\"],\"url\":\"https:\\\/\\\/www.jobcloud.ch\\\/c\\\/de-ch\\\/blog\\\/author\\\/msteger\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vorlagen f\u00fcr Stellenausschreibungen | JobCloud","description":"Auf JobCloud finden Sie unter \u00abRatgeber & Checklisten\u00bb neu den Bereich \u00abVorlagen\u00bb. Entdecken Sie dort eine allgemeine Vorlage f\u00fcr eine Stellenausschreibung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jobcloud.ch\/c\/de-ch\/blog\/vorlagen-stellenausschreibungen\/","og_locale":"de_DE","og_type":"article","og_title":"Vorlagen f\u00fcr Stellenausschreibungen | JobCloud","og_description":"Auf JobCloud finden Sie unter \u00abRatgeber & Checklisten\u00bb neu den Bereich \u00abVorlagen\u00bb. Entdecken Sie dort eine allgemeine Vorlage f\u00fcr eine Stellenausschreibung","og_url":"https:\/\/www.jobcloud.ch\/c\/de-ch\/blog\/vorlagen-stellenausschreibungen\/","og_site_name":"JobCloud","article_published_time":"2022-01-16T06:21:31+00:00","article_modified_time":"2022-04-12T13:26:07+00:00","og_image":[{"width":1400,"height":719,"url":"https:\/\/www.jobcloud.ch\/wp-content\/uploads\/2019\/01\/rawpixel-1046262-1.jpg","type":"image\/jpeg"}],"author":"Mathias Steger","twitter_card":"summary_large_image","twitter_misc":{"Geschrieben von":"Mathias Steger"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jobcloud.ch\/c\/de-ch\/blog\/vorlagen-stellenausschreibungen\/#article","isPartOf":{"@id":"https:\/\/www.jobcloud.ch\/c\/de-ch\/blog\/vorlagen-stellenausschreibungen\/"},"author":{"name":"Mathias Steger","@id":"https:\/\/www.jobcloud.ch\/c\/de-ch\/#\/schema\/person\/1f8af37d814987189cbef1b058a084a4"},"headline":"Vorlagen f\u00fcr Stellenausschreibungen","datePublished":"2022-01-16T06:21:31+00:00","dateModified":"2022-04-12T13:26:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.jobcloud.ch\/c\/de-ch\/blog\/vorlagen-stellenausschreibungen\/"},"wordCount":4,"commentCount":0,"publisher":{"@id":"https:\/\/www.jobcloud.ch\/c\/de-ch\/#organization"},"image":{"@id":"https:\/\/www.jobcloud.ch\/c\/de-ch\/blog\/vorlagen-stellenausschreibungen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.jobcloud.ch\/wp-content\/uploads\/2019\/01\/rawpixel-1046262-1.jpg","keywords":["Inserat","Inseratvorlage","Jobinserat","Stellenausschreibung","Template","Vorlage"],"articleSection":["Recruiting"],"inLanguage":"de-CH","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.jobcloud.ch\/c\/de-ch\/blog\/vorlagen-stellenausschreibungen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.jobcloud.ch\/c\/de-ch\/blog\/vorlagen-stellenausschreibungen\/","url":"https:\/\/www.jobcloud.ch\/c\/de-ch\/blog\/vorlagen-stellenausschreibungen\/","name":"Vorlagen f\u00fcr Stellenausschreibungen | JobCloud","isPartOf":{"@id":"https:\/\/www.jobcloud.ch\/c\/de-ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.jobcloud.ch\/c\/de-ch\/blog\/vorlagen-stellenausschreibungen\/#primaryimage"},"image":{"@id":"https:\/\/www.jobcloud.ch\/c\/de-ch\/blog\/vorlagen-stellenausschreibungen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.jobcloud.ch\/wp-content\/uploads\/2019\/01\/rawpixel-1046262-1.jpg","datePublished":"2022-01-16T06:21:31+00:00","dateModified":"2022-04-12T13:26:07+00:00","description":"Auf JobCloud finden Sie unter \u00abRatgeber & Checklisten\u00bb neu den Bereich \u00abVorlagen\u00bb. Entdecken Sie dort eine allgemeine Vorlage f\u00fcr eine Stellenausschreibung","breadcrumb":{"@id":"https:\/\/www.jobcloud.ch\/c\/de-ch\/blog\/vorlagen-stellenausschreibungen\/#breadcrumb"},"inLanguage":"de-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jobcloud.ch\/c\/de-ch\/blog\/vorlagen-stellenausschreibungen\/"]}]},{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/www.jobcloud.ch\/c\/de-ch\/blog\/vorlagen-stellenausschreibungen\/#primaryimage","url":"https:\/\/www.jobcloud.ch\/wp-content\/uploads\/2019\/01\/rawpixel-1046262-1.jpg","contentUrl":"https:\/\/www.jobcloud.ch\/wp-content\/uploads\/2019\/01\/rawpixel-1046262-1.jpg","width":1400,"height":719},{"@type":"BreadcrumbList","@id":"https:\/\/www.jobcloud.ch\/c\/de-ch\/blog\/vorlagen-stellenausschreibungen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Wettbewerbskommission stimmt \u00dcbernahme von jobs.ch durch Ringier und Tamedia zu","item":"https:\/\/www.jobcloud.ch\/c\/de-ch\/blog\/press-release\/wettbewerbskommission-stimmt-ubernahme-von-jobs-ch-durch-ringier-und-tamedia-zu\/"},{"@type":"ListItem","position":2,"name":"Vorlagen f\u00fcr Stellenausschreibungen"}]},{"@type":"WebSite","@id":"https:\/\/www.jobcloud.ch\/c\/de-ch\/#website","url":"https:\/\/www.jobcloud.ch\/c\/de-ch\/","name":"JobCloud","description":"JobCloud is the leading job portal for jobseekers in Switzerland","publisher":{"@id":"https:\/\/www.jobcloud.ch\/c\/de-ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jobcloud.ch\/c\/de-ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"},{"@type":"Organization","@id":"https:\/\/www.jobcloud.ch\/c\/de-ch\/#organization","name":"JobCloud","url":"https:\/\/www.jobcloud.ch\/c\/de-ch\/","logo":{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/www.jobcloud.ch\/c\/de-ch\/#\/schema\/logo\/image\/","url":"https:\/\/www.jobcloud.ch\/wp-content\/uploads\/2020\/02\/jobcloude-logo.svg","contentUrl":"https:\/\/www.jobcloud.ch\/wp-content\/uploads\/2020\/02\/jobcloude-logo.svg","width":160,"height":37,"caption":"JobCloud"},"image":{"@id":"https:\/\/www.jobcloud.ch\/c\/de-ch\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.jobcloud.ch\/c\/de-ch\/#\/schema\/person\/1f8af37d814987189cbef1b058a084a4","name":"Mathias Steger","image":{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/www.jobcloud.ch\/wp-content\/uploads\/2021\/01\/Mathias-Steger_avatar-96x96.png","url":"https:\/\/www.jobcloud.ch\/wp-content\/uploads\/2021\/01\/Mathias-Steger_avatar-96x96.png","contentUrl":"https:\/\/www.jobcloud.ch\/wp-content\/uploads\/2021\/01\/Mathias-Steger_avatar-96x96.png","caption":"Mathias Steger"},"sameAs":["https:\/\/www.linkedin.com\/in\/mathias-steger-52164a11b?"],"url":"https:\/\/www.jobcloud.ch\/c\/de-ch\/blog\/author\/msteger\/"}]}},"_links":{"self":[{"href":"https:\/\/www.jobcloud.ch\/c\/de-ch\/wp-json\/wp\/v2\/posts\/18266","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jobcloud.ch\/c\/de-ch\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jobcloud.ch\/c\/de-ch\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jobcloud.ch\/c\/de-ch\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jobcloud.ch\/c\/de-ch\/wp-json\/wp\/v2\/comments?post=18266"}],"version-history":[{"count":0,"href":"https:\/\/www.jobcloud.ch\/c\/de-ch\/wp-json\/wp\/v2\/posts\/18266\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jobcloud.ch\/c\/de-ch\/wp-json\/wp\/v2\/media\/18271"}],"wp:attachment":[{"href":"https:\/\/www.jobcloud.ch\/c\/de-ch\/wp-json\/wp\/v2\/media?parent=18266"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jobcloud.ch\/c\/de-ch\/wp-json\/wp\/v2\/categories?post=18266"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jobcloud.ch\/c\/de-ch\/wp-json\/wp\/v2\/tags?post=18266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}